{"id":4896,"date":"2023-09-20T18:17:19","date_gmt":"2023-09-20T17:17:19","guid":{"rendered":"https:\/\/www.novakidschool.com\/es\/blog\/?p=4896"},"modified":"2023-10-17T13:58:40","modified_gmt":"2023-10-17T12:58:40","slug":"participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid","status":"publish","type":"post","link":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/","title":{"rendered":"Comparte las Historias felices de Novakid y consigue clases gratis"},"content":{"rendered":"  <section class=\"section blogHeader\" id=\"blogHeader-block_5ab1796e520b172006d718bdf10ea5e4\">\n      <div class=\"blogHeader__wrapper\">\n                              <div class=\"blogHeader__image\">\n              <a href=\"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png\" class=\"glightbox\">\n                <img decoding=\"async\" src=\"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png\" alt=\"Comparte las Historias felices de Novakid y consigue clases gratis\" class=\"blogHeader__imageItem\" srcset=\"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video-300x180.png 300w, https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video-768x460.png 768w, https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png 1024w\" style=\"width:100%; aspect-ratio:1024\/613;\"> \n              <\/a>\n          <\/div>\n          \n      <\/div>\n  <\/section>\n\n  \n\n\n  <section class=\"section blogHeadingText\" id=\"blogHeadingText-block_7420b7c30b7f82c7bfcd835e19e8a3d7\">\n    <div class=\"blogHeadingText__wrapper\" >\n        <div class=\"blogHeadingText__heading\">\n            <h2 class=\"blogHeadingText__headingItem\" data-blog-heading data-section-id=\"blogHeadingText-block_7420b7c30b7f82c7bfcd835e19e8a3d7\">\n                \u00a1Participa en la campa\u00f1a Historias felices de Novakid y consigue clases de ingl\u00e9s gratis para tus hijos!            <\/h2>\n        <\/div>\n        <div class=\"blogHeadingText__content\">\n            <p><span style=\"font-weight: 400;\">\u00a1Llamamos a todos los dedicados padres de Novakid! Esta es vuestra oportunidad de recibir clases gratuitas para vuestros hijos simplemente por compartir vuestro cari\u00f1o por nuestra <\/span><a href=\"https:\/\/www.novakidschool.com\/\"><span style=\"font-weight: 400;\">escuela de ingl\u00e9s online<\/span><\/a><span style=\"font-weight: 400;\">. \u00a1Participad en nuestra emocionante campa\u00f1a!<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Vuestra recompensa<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00a1Valoramos vuestra dedicaci\u00f3n, as\u00ed que cada participante podr\u00e1 recibir hasta 8 clases GRATIS de ingl\u00e9s de Novakid!\u00a0<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">C\u00f3mo participar\u00a0<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u00a1Muy sencillo! Grabad un v\u00eddeo acerca de vuestra experiencia con Novakid. Podr\u00e9is incluir tanto a un estudiante de Novakid con su madre o padre, o solo a uno de los padres hablando si as\u00ed lo prefer\u00eds.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Detalles<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Si te apasiona Novakid, prep\u00e1rate para brillar en nuestra campa\u00f1a. Demuestra tu cari\u00f1o y entusiasmo siguiendo estos simples pasos:<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Estructura:<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Crea una rese\u00f1a en v\u00eddeo siguiendo esta estructura:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Introducci\u00f3n: Comparte tu nombre y lugar de residencia.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Acerca de tu hijo\/a: Menciona el nombre, la edad de tu hijo\/a, y cu\u00e1nto tiempo lleva estudiando en Novakid.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">El porqu\u00e9 de tu elecci\u00f3n: \u00bfQu\u00e9 te llev\u00f3 a elegir Novakid para el aprendizaje de ingl\u00e9s online?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lo que m\u00e1s destaca tu hijo\/a: \u00bfQu\u00e9 es lo que m\u00e1s le gusta a tu hijo\/a de las clases de ingl\u00e9s de Novakid?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Qu\u00e9 hace que Novakid sea especial: destaca lo que diferencia a Novakid y tus caracter\u00edsticas favoritas.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inmersi\u00f3n en el ingl\u00e9s: Comparte tu punto de vista sobre tener clases 100% en ingl\u00e9s.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Conveniencia de la cuenta de padres: Comparte tus ideas sobre el uso de tu cuenta de padres.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Duraci\u00f3n de la clase: Danos tu perspectiva sobre la duraci\u00f3n de las clases.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Novakid Game World: Danos tu opini\u00f3n sobre esta funci\u00f3n y sus beneficios en comparaci\u00f3n con las escuelas presenciales.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Progreso visto: Describe cualquier mejora que hayas apreciado en el nivel de ingl\u00e9s de tu hijo\/a.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ventajas de aprender ingl\u00e9s: Explica las razones por las que tu hijo\/a est\u00e9 recibiendo clases de ingl\u00e9s.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Descubrimiento de Novakid: \u00bfC\u00f3mo conociste nuestra escuela?<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Recomendaci\u00f3n: \u00bfRecomendar\u00edas Novakid a otros padres y madres? \u00bfPor qu\u00e9?<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400;\">Instrucciones de env\u00edo<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Para recibir las clases de ingl\u00e9s gratis, debes seguir estas directrices:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Graba cada respuesta como un archivo de v\u00eddeo separado (hasta 13 v\u00eddeos).<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">C\u00e9ntrate en conseguir la mejor calidad posible. Realiza varias tomas del mismo v\u00eddeo si lo consideras necesario.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aseg\u00farate de que los v\u00eddeos no est\u00e1n editados, que est\u00e1n grabados en 4K o Full HD, con buena iluminaci\u00f3n y libres de ruidos externos.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ponte ropa sin dise\u00f1os elaborados ni colores demasiado vivos. No lleves ropa roja o negra.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Para los v\u00eddeos selfie, mant\u00e9n siempre contacto visual con la c\u00e1mara.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Para puntos adicionales, incluye un v\u00eddeo de tu hijo\/a durante una clase de Novakid.<\/span><\/li>\n<\/ul>\n<h3><span style=\"font-weight: 400;\">Criterios de evaluaci\u00f3n:<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La cantidad de clases gratis que obtendr\u00e1s depender\u00e1 de los siguientes criterios:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Calidad del v\u00eddeo<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Creatividad<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tu consentimiento para que publiquemos el v\u00eddeo en internet<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><\/td>\n<td><b>Calidad<\/b><\/td>\n<td><b>Creatividad<\/b><\/td>\n<td><b>Consentimiento para publicar en redes sociales<\/b><\/td>\n<td><b>Proporcionar datos personales<\/b><\/td>\n<td><b>N\u00famero de clases<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>Excelente<\/b><\/td>\n<td><b>2<\/b><\/td>\n<td><b>2<\/b><\/td>\n<td><b>2<\/b><\/td>\n<td><b>2<\/b><\/td>\n<td><b>8<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>Bien<\/b><\/td>\n<td><b>1<\/b><\/td>\n<td><b>1<\/b><\/td>\n<td><b>1<\/b><\/td>\n<td><b>1<\/b><\/td>\n<td><b>4<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>Normal<\/b><\/td>\n<td><b>0,5<\/b><\/td>\n<td><b>0,5<\/b><\/td>\n<td><b>0,5<\/b><\/td>\n<td><b>0,5<\/b><\/td>\n<td><b>2<\/b><\/td>\n<\/tr>\n<tr>\n<td><b>Mediocre<\/b><\/td>\n<td><b>0<\/b><\/td>\n<td><b>0<\/b><\/td>\n<td><b>0<\/b><\/td>\n<td><b>0<\/b><\/td>\n<td><b>0<\/b><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h3><span style=\"font-weight: 400;\">Fechas<\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inicio de la campa\u00f1a: 15 de septiembre de 2023<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fecha l\u00edmite de env\u00edo: 30 de noviembre de 2023<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Revisi\u00f3n final de los videos y concesi\u00f3n de las clases: 10 de diciembre de 2023<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u00a1Prep\u00e1rate para compartir tu historia con Novakid! Deja que tu entusiasmo brille por s\u00ed mismo y recibe clases gratis.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por favor, env\u00eda tu v\u00eddeo y cualquier consulta a Inessa Morozova en <\/span><a href=\"mailto:imorozova@novakidschool.com\"><span style=\"font-weight: 400;\">imorozova@novakidschool.com<\/span><\/a><span style=\"font-weight: 400;\">. \u00a1Celebremos juntos la alegr\u00eda de aprender con la comunidad de Novakid!<\/span><\/p>\n        <\/div>\n    <\/div>\n  <\/section>\n","protected":false},"excerpt":{"rendered":"<p> \u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!<\/p>\n","protected":false},"author":1,"featured_media":4897,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-4896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Participa en la campa\u00f1a Historias felices de Novakid y ll\u00e9vate clases particulares de ingl\u00e9s gratis para tus hijos con Novakid!<\/title>\n<meta name=\"description\" content=\"\u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Participa en la campa\u00f1a Historias felices de Novakid y ll\u00e9vate clases particulares de ingl\u00e9s gratis para tus hijos con Novakid!\" \/>\n<meta property=\"og:description\" content=\"\u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/\" \/>\n<meta property=\"og:site_name\" content=\"Novakid\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T17:17:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T12:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Novakid\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Novakid\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Participa en la campa\u00f1a Historias felices de Novakid y ll\u00e9vate clases particulares de ingl\u00e9s gratis para tus hijos con Novakid!","description":"\u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Participa en la campa\u00f1a Historias felices de Novakid y ll\u00e9vate clases particulares de ingl\u00e9s gratis para tus hijos con Novakid!","og_description":"\u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!","og_url":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/","og_site_name":"Novakid","article_published_time":"2023-09-20T17:17:19+00:00","article_modified_time":"2023-10-17T12:58:40+00:00","og_image":[{"width":1024,"height":613,"url":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png","type":"image\/png"}],"author":"Novakid","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Novakid"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#article","isPartOf":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/"},"author":{"name":"Novakid","@id":"https:\/\/www.novakidschool.com\/es\/blog\/#\/schema\/person\/97c36458519ae32de5744e9a8ea02aa7"},"headline":"Comparte las Historias felices de Novakid y consigue clases gratis","datePublished":"2023-09-20T17:17:19+00:00","dateModified":"2023-10-17T12:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/"},"wordCount":10,"commentCount":0,"publisher":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/#organization"},"image":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png","articleSection":["Concursos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/","url":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/","name":"\u00a1Participa en la campa\u00f1a Historias felices de Novakid y ll\u00e9vate clases particulares de ingl\u00e9s gratis para tus hijos con Novakid!","isPartOf":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#primaryimage"},"image":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png","datePublished":"2023-09-20T17:17:19+00:00","dateModified":"2023-10-17T12:58:40+00:00","description":"\u00a1Comparte tu cari\u00f1o por Novakid en un v\u00eddeo y recibe hasta 8 clases de ingl\u00e9s gratis! \u00a1\u00danete a la comunidad de Novakid y disfruta de todos sus beneficios!","breadcrumb":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#primaryimage","url":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png","contentUrl":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2023\/09\/Video.png","width":1024,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/www.novakidschool.com\/es\/blog\/participa-en-la-campana-historias-felices-de-novakid-y-llevate-clases-particulares-de-ingles-gratis-para-tus-hijos-con-novakid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.novakidschool.com\/es\/blog\/"},{"@type":"ListItem","position":2,"name":"Comparte las Historias felices de Novakid y consigue clases gratis"}]},{"@type":"WebSite","@id":"https:\/\/www.novakidschool.com\/es\/blog\/#website","url":"https:\/\/www.novakidschool.com\/es\/blog\/","name":"Novakid","description":"Novakid blog Spain","publisher":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.novakidschool.com\/es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.novakidschool.com\/es\/blog\/#organization","name":"Novakid","url":"https:\/\/www.novakidschool.com\/es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.novakidschool.com\/es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2022\/03\/logo-novakid.svg","contentUrl":"https:\/\/www.novakidschool.com\/es\/blog\/wp-content\/uploads\/2022\/03\/logo-novakid.svg","width":268,"height":71,"caption":"Novakid"},"image":{"@id":"https:\/\/www.novakidschool.com\/es\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.novakidschool.com\/es\/blog\/#\/schema\/person\/97c36458519ae32de5744e9a8ea02aa7","name":"Novakid"}]}},"_links":{"self":[{"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/posts\/4896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/comments?post=4896"}],"version-history":[{"count":8,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/posts\/4896\/revisions"}],"predecessor-version":[{"id":4908,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/posts\/4896\/revisions\/4908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/media\/4897"}],"wp:attachment":[{"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/media?parent=4896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/categories?post=4896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novakidschool.com\/es\/blog\/wp-json\/wp\/v2\/tags?post=4896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}